{"id":1218,"date":"2021-11-10T11:41:07","date_gmt":"2021-11-10T14:41:07","guid":{"rendered":"http:\/\/redemeridional.com.br\/serra\/?p=1218"},"modified":"2021-11-10T11:41:07","modified_gmt":"2021-11-10T14:41:07","slug":"hospital-se-torna-primeiro-centro-de-habilitacao-em-cirurgias-roboticas-do-espirito-santo-pelo-colegio-brasileiro-de-cirurgioes-cbc","status":"publish","type":"post","link":"https:\/\/redemeridional.com.br\/serra\/hospital-se-torna-primeiro-centro-de-habilitacao-em-cirurgias-roboticas-do-espirito-santo-pelo-colegio-brasileiro-de-cirurgioes-cbc\/","title":{"rendered":"Hospital se torna primeiro Centro de Habilita\u00e7\u00e3o em Cirurgias Rob\u00f3ticas do Esp\u00edrito Santo pelo Col\u00e9gio Brasileiro de Cirurgi\u00f5es &#8211; CBC"},"content":{"rendered":"\n<p>O Centro de Treinamento em Cirurgia Rob\u00f3tica do Meridional Cariacica foi aprovado como o primeiro Centro de Habilita\u00e7\u00e3o em Cirurgias Rob\u00f3ticas do Esp\u00edrito Santo, apto a formar e especializar cirurgi\u00f5es do Estado e do Brasil. O reconhecimento e credenciamento foram feitos pelo Col\u00e9gio Brasileiro de Cirurgi\u00f5es (CBC), maior entidade de cirurgi\u00f5es da Am\u00e9rica Latina.<\/p>\n\n\n\n<p>O local foi vistoriado pelo m\u00e9dico Leandro Totti, membro da Comiss\u00e3o de Cirurgia Minimamente Invasiva e Rob\u00f3tica do CBC. De acordo com o cirurgi\u00e3o e coordenador da Resid\u00eancia M\u00e9dica de Cirurgia Geral do Meridional Cariacica, Gustavo Peixoto, isso significa, na pr\u00e1tica, que o hospital tem um time de tutores locais e um centro formador local de cirurgi\u00f5es rob\u00f3ticos aptos a emitir certificado de habilita\u00e7\u00e3o chancelado pelo CBC.<\/p>\n\n\n\n<p>\u201cEste reconhecimento abre um leque ainda maior de possibilidades para todos os cirurgi\u00f5es do Esp\u00edrito Santo que t\u00eam interesse em se habilitar na cirurgia rob\u00f3tica e j\u00e1 come\u00e7a, tamb\u00e9m, a receber cirurgi\u00f5es de outros Estados\u201d, explicou Peixoto.<\/p>\n\n\n\n<p>Cirurgia Rob\u00f3tica<\/p>\n\n\n\n<p>A utiliza\u00e7\u00e3o da tecnologia de cirurgia rob\u00f3tica traz seguran\u00e7a e vantagens tanto para o paciente quanto para o cirurgi\u00e3o. O uso do sistema de cirurgia Da Vinci Xi Surgical System permite ao cirurgi\u00e3o visualizar a \u00e1rea operat\u00f3ria com alta resolu\u00e7\u00e3o, e a utiliza\u00e7\u00e3o de bra\u00e7os cir\u00fargicos de um cent\u00edmetro de di\u00e2metro minimiza as incis\u00f5es cir\u00fargicas, diminuindo as dores, acelerando a recupera\u00e7\u00e3o e o retorno \u00e0s atividades di\u00e1rias do paciente. Esse processo permite menos contato entre o tecido inferior interior exposto e o texto dispositivo cir\u00fargico, reduzindo bastante o risco de infec\u00e7\u00e3o p\u00f3s-operat\u00f3rio.<\/p>\n\n\n\n<p>O Meridional foi o primeiro a realizar uma cirurgia bari\u00e1trica no Estado com cirurgia rob\u00f3tica, al\u00e9m de ser pioneiro tamb\u00e9m em hepatectomia (cirurgia do f\u00edgado), colectomia (intestino), histerectomia (retirada do \u00fatero), herniorrafia (de h\u00e9rnia), e outras opera\u00e7\u00f5es complexas utilizando o m\u00e9todo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro de Treinamento em Cirurgia Rob\u00f3tica do Meridional Cariacica foi aprovado como o primeiro Centro de Habilita\u00e7\u00e3o em Cirurgias Rob\u00f3ticas do Esp\u00edrito Santo, apto a formar e especializar cirurgi\u00f5es do Estado e do Brasil. O reconhecimento e credenciamento foram feitos pelo Col\u00e9gio Brasileiro de Cirurgi\u00f5es (CBC), maior entidade de cirurgi\u00f5es da Am\u00e9rica Latina. O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/posts\/1218"}],"collection":[{"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/comments?post=1218"}],"version-history":[{"count":1,"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/posts\/1218\/revisions"}],"predecessor-version":[{"id":1220,"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/posts\/1218\/revisions\/1220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/media\/1219"}],"wp:attachment":[{"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/media?parent=1218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/categories?post=1218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redemeridional.com.br\/serra\/wp-json\/wp\/v2\/tags?post=1218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}